{"id":366,"date":"2024-08-01T09:05:48","date_gmt":"2024-08-01T09:05:48","guid":{"rendered":"https:\/\/nopassdev.com\/?p=366"},"modified":"2025-07-02T16:08:29","modified_gmt":"2025-07-02T16:08:29","slug":"wordpress-pin-post-methods","status":"publish","type":"post","link":"https:\/\/nopassdev.com\/es\/wordpress-pin-post-methods\/","title":{"rendered":"3 formas de publicar en WordPress"},"content":{"rendered":"<p>\u00a1En el uso de WordPress para construir un blog, por defecto, los art\u00edculos ser\u00e1n ordenados por tiempo, cada vez que el lanzamiento de un nuevo art\u00edculo se mostrar\u00e1 autom\u00e1ticamente en la primera posici\u00f3n del blog, por lo que el sitio tiene un nuevo art\u00edculo puede ser la primera vez para los visitantes a ver!<\/p>\n\n\n\n<p>\u00a1Pero hay veces en que no queremos mostrar los \u00faltimos art\u00edculos en la parte superior del sitio, pero quieren mostrar algunos contenidos importantes, tales como anuncios de sitios web, contenido promocional, etc, en este momento usted necesita para configurar los art\u00edculos de WordPress superior, el siguiente paso para ense\u00f1arle c\u00f3mo la parte superior del art\u00edculo de WordPress!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u65b9\u6cd5\u4e00-\u5728\u53e4\u817e\u5821\u7f16\u8f91\u5668\u4e2d\u7f6e\u9876\u6587\u7ae0\">M\u00e9todo 1: Art\u00edculo superior en el editor Gutenberg<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701183042.jpg\" alt=\"wordpress \u8bbe\u7f6e\u6587\u7ae0\u7f6e\u9876\" class=\"wp-image-76390\"\/><\/figure>\n\n\n\n<p>Ahora el editor predeterminado de WordPress es la nueva versi\u00f3n del editor Gutenberg, Gutenberg muchas opciones en la configuraci\u00f3n son m\u00e1s convenientes, una de las mejoras obvias es el art\u00edculo superior, justo en el lado derecho de la configuraci\u00f3n del documento marque \"<strong>Opciones de topping en los blogs<\/strong>\" al principio del art\u00edculo<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u65b9\u6cd5\u4e8c-\u5728\u7ecf\u5178\u7f16\u8f91\u5668\u4e2d\u7f6e\u9876\u6587\u7ae0\">M\u00e9todo 2: Art\u00edculo superior en el editor cl\u00e1sico<\/h2>\n\n\n\n<p>El editor cl\u00e1sico ofrece una funci\u00f3n de encabezado de entrada, pero est\u00e1 oculta por defecto entre otras funciones.<\/p>\n\n\n\n<p>Primero tiene que encontrar el m\u00f3dulo de publicaci\u00f3n en la parte derecha, que tiene una opci\u00f3n llamada<strong>visibilidad<\/strong>Haga clic en el bot\u00f3n Editar situado junto a \u00e9l.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701184618.jpg\" alt=\"\" class=\"wp-image-76391\"\/><\/figure>\n\n\n\n<p>Entonces ver\u00e1s que hay algo llamado&nbsp;<strong>Colocar los art\u00edculos en la parte superior de la p\u00e1gina de inicio<\/strong>&nbsp;para marcar la casilla que encabeza el art\u00edculo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701184749.jpg\" alt=\"\" class=\"wp-image-76392\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u65b9\u6cd5\u4e09-\u5728\u6587\u7ae0\u5217\u8868\u4e2d\u7f6e\u9876\u6587\u7ae0\">M\u00e9todo 3: Primeros art\u00edculos de la lista de art\u00edculos<\/h2>\n\n\n\n<p>Adem\u00e1s de las dos formas anteriores de establecer la parte superior al editar un art\u00edculo, hay otra forma de establecer la parte superior en la lista de art\u00edculos, que es m\u00e1s adecuada para operaciones r\u00e1pidas y por lotes<\/p>\n\n\n\n<p>Abra el fondo de la lista de art\u00edculos, y encontrar el art\u00edculo que desea superior, cuando el rat\u00f3n se cierne sobre el art\u00edculo correspondiente, habr\u00e1 una llamada operaci\u00f3n de edici\u00f3n r\u00e1pida, haga clic en el elemento<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701185252-800x294.jpg\" alt=\"\" class=\"wp-image-76393\"\/><\/figure>\n\n\n\n<p>garrapata&nbsp;<strong>Top this article<\/strong>Si desea a\u00f1adir un nuevo art\u00edculo a la lista, puede hacerlo pulsando en el siguiente enlace<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701185411-800x346.jpg\" alt=\"\" class=\"wp-image-76394\"\/><\/figure>","protected":false},"excerpt":{"rendered":"<p>\u5728\u4f7f\u7528WordPress\u642d\u5efa\u535a\u5ba2\u65f6\uff0c\u9ed8\u8ba4\u60c5\u51b5\u4e0b\u4f1a\u6309\u65f6\u95f4\u5bf9\u6587\u7ae0\u8fdb\u884c\u6392\u5e8f\uff0c\u6bcf\u6b21\u53d1\u5e03\u65b0\u7684\u6587\u7ae0\u90fd\u4f1a\u81ea\u52a8\u5c55\u793a\u5728\u535a\u5ba2\u7684\u7b2c\u4e00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-366","post","type-post","status-publish","format-standard","hentry","category-wordpress-tutorial"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5 - \u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nopassdev.com\/es\/wordpress-pin-post-methods\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5 - \u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546\" \/>\n<meta property=\"og:description\" content=\"\u5728\u4f7f\u7528WordPress\u642d\u5efa\u535a\u5ba2\u65f6\uff0c\u9ed8\u8ba4\u60c5\u51b5\u4e0b\u4f1a\u6309\u65f6\u95f4\u5bf9\u6587\u7ae0\u8fdb\u884c\u6392\u5e8f\uff0c\u6bcf\u6b21\u53d1\u5e03\u65b0\u7684\u6587\u7ae0\u90fd\u4f1a\u81ea\u52a8\u5c55\u793a\u5728\u535a\u5ba2\u7684\u7b2c\u4e00 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nopassdev.com\/es\/wordpress-pin-post-methods\/\" \/>\n<meta property=\"og:site_name\" content=\"\u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-01T09:05:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T16:08:29+00:00\" \/>\n<meta name=\"author\" content=\"Nopass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nopass\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/\"},\"author\":{\"name\":\"Nopass\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#\\\/schema\\\/person\\\/10c72918e517d5694cdb56ed20f0eba7\"},\"headline\":\"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5\",\"datePublished\":\"2024-08-01T09:05:48+00:00\",\"dateModified\":\"2025-07-02T16:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/themeforwp.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/20200701183042.jpg\",\"articleSection\":[\"Wordpress\u6559\u7a0b\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/\",\"url\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/\",\"name\":\"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5 - \u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/themeforwp.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/20200701183042.jpg\",\"datePublished\":\"2024-08-01T09:05:48+00:00\",\"dateModified\":\"2025-07-02T16:08:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#primaryimage\",\"url\":\"https:\\\/\\\/themeforwp.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/20200701183042.jpg\",\"contentUrl\":\"https:\\\/\\\/themeforwp.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/20200701183042.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/wordpress-pin-post-methods\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/nopassdev.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/\",\"name\":\"\u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#organization\",\"name\":\"\u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546\",\"url\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nopassdev.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/LOGO-NEW.jpg\",\"contentUrl\":\"https:\\\/\\\/nopassdev.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/LOGO-NEW.jpg\",\"width\":1822,\"height\":306,\"caption\":\"\u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546\"},\"image\":{\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nopassdev.com\\\/zh\\\/#\\\/schema\\\/person\\\/10c72918e517d5694cdb56ed20f0eba7\",\"name\":\"Nopass\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8717d323563ed7c90a695bacdb516c285d94c51ce7947adb6c33f07577e6ac8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8717d323563ed7c90a695bacdb516c285d94c51ce7947adb6c33f07577e6ac8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8717d323563ed7c90a695bacdb516c285d94c51ce7947adb6c33f07577e6ac8?s=96&d=mm&r=g\",\"caption\":\"Nopass\"},\"sameAs\":[\"https:\\\/\\\/nopassdev.com\"],\"url\":\"https:\\\/\\\/nopassdev.com\\\/es\\\/author\\\/minglifa2022gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres formas de destacar entradas en WordPress - Proveedor de servicios de creaci\u00f3n de sitios web internacionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nopassdev.com\/es\/wordpress-pin-post-methods\/","og_locale":"es_MX","og_type":"article","og_title":"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5 - \u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546","og_description":"\u5728\u4f7f\u7528WordPress\u642d\u5efa\u535a\u5ba2\u65f6\uff0c\u9ed8\u8ba4\u60c5\u51b5\u4e0b\u4f1a\u6309\u65f6\u95f4\u5bf9\u6587\u7ae0\u8fdb\u884c\u6392\u5e8f\uff0c\u6bcf\u6b21\u53d1\u5e03\u65b0\u7684\u6587\u7ae0\u90fd\u4f1a\u81ea\u52a8\u5c55\u793a\u5728\u535a\u5ba2\u7684\u7b2c\u4e00 [&hellip;]","og_url":"https:\/\/nopassdev.com\/es\/wordpress-pin-post-methods\/","og_site_name":"\u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546","article_published_time":"2024-08-01T09:05:48+00:00","article_modified_time":"2025-07-02T16:08:29+00:00","author":"Nopass","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nopass"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#article","isPartOf":{"@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/"},"author":{"name":"Nopass","@id":"https:\/\/nopassdev.com\/zh\/#\/schema\/person\/10c72918e517d5694cdb56ed20f0eba7"},"headline":"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5","datePublished":"2024-08-01T09:05:48+00:00","dateModified":"2025-07-02T16:08:29+00:00","mainEntityOfPage":{"@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/nopassdev.com\/zh\/#organization"},"image":{"@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#primaryimage"},"thumbnailUrl":"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701183042.jpg","articleSection":["Wordpress\u6559\u7a0b"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/","url":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/","name":"Tres formas de destacar entradas en WordPress - Proveedor de servicios de creaci\u00f3n de sitios web internacionales","isPartOf":{"@id":"https:\/\/nopassdev.com\/zh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#primaryimage"},"image":{"@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#primaryimage"},"thumbnailUrl":"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701183042.jpg","datePublished":"2024-08-01T09:05:48+00:00","dateModified":"2025-07-02T16:08:29+00:00","breadcrumb":{"@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nopassdev.com\/wordpress-pin-post-methods\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#primaryimage","url":"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701183042.jpg","contentUrl":"https:\/\/themeforwp.net\/wp-content\/uploads\/2020\/07\/20200701183042.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nopassdev.com\/wordpress-pin-post-methods\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/nopassdev.com\/"},{"@type":"ListItem","position":2,"name":"WordPress \u7f6e\u9876\u6587\u7ae0\u76843\u79cd\u65b9\u6cd5"}]},{"@type":"WebSite","@id":"https:\/\/nopassdev.com\/zh\/#website","url":"https:\/\/nopassdev.com\/zh\/","name":"Proveedores de servicios web transfronterizos","description":"","publisher":{"@id":"https:\/\/nopassdev.com\/zh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nopassdev.com\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nopassdev.com\/zh\/#organization","name":"Proveedores de servicios web transfronterizos","url":"https:\/\/nopassdev.com\/zh\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nopassdev.com\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/nopassdev.com\/wp-content\/uploads\/2025\/07\/LOGO-NEW.jpg","contentUrl":"https:\/\/nopassdev.com\/wp-content\/uploads\/2025\/07\/LOGO-NEW.jpg","width":1822,"height":306,"caption":"\u8de8\u5883\u5efa\u7ad9\u670d\u52a1\u5546"},"image":{"@id":"https:\/\/nopassdev.com\/zh\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nopassdev.com\/zh\/#\/schema\/person\/10c72918e517d5694cdb56ed20f0eba7","name":"Nopass","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b8717d323563ed7c90a695bacdb516c285d94c51ce7947adb6c33f07577e6ac8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b8717d323563ed7c90a695bacdb516c285d94c51ce7947adb6c33f07577e6ac8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8717d323563ed7c90a695bacdb516c285d94c51ce7947adb6c33f07577e6ac8?s=96&d=mm&r=g","caption":"Nopass"},"sameAs":["https:\/\/nopassdev.com"],"url":"https:\/\/nopassdev.com\/es\/author\/minglifa2022gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/posts\/366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/comments?post=366"}],"version-history":[{"count":1,"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/posts\/366\/revisions"}],"predecessor-version":[{"id":367,"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/posts\/366\/revisions\/367"}],"wp:attachment":[{"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/media?parent=366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/categories?post=366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nopassdev.com\/es\/wp-json\/wp\/v2\/tags?post=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}